{"id":2536,"date":"2022-12-02T15:21:37","date_gmt":"2022-12-02T14:21:37","guid":{"rendered":"https:\/\/www.divella.it\/it\/?post_type=prodotti&#038;p=2536"},"modified":"2026-07-15T10:02:24","modified_gmt":"2026-07-15T08:02:24","slug":"ottimini-riso-e-mais","status":"publish","type":"prodotti","link":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/","title":{"rendered":"Ottimini riso e mais"},"excerpt":{"rendered":"<p>Caratterizzato dal perfetto connubio fra riso e mais soffiati che lo rendono gustoso e croccante,  pu\u00f2 essere consumato in qualsiasi momento della giornata, anche come snack.<\/p>\n","protected":false},"featured_media":3694,"template":"","tipo-prodotto":[41,85],"class_list":["post-2536","prodotti","type-prodotti","status-publish","has-post-thumbnail","hentry","tipo-prodotto-biscotti-e-croissant","tipo-prodotto-biscotti-ottimini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ottimini riso e mais - Divella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ottimini riso e mais - Divella\" \/>\n<meta property=\"og:description\" content=\"Caratterizzato dal perfetto connubio fra riso e mais soffiati che lo rendono gustoso e croccante, pu\u00f2 essere consumato in qualsiasi momento della giornata, anche come snack.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/\" \/>\n<meta property=\"og:site_name\" content=\"Divella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Divella.IT\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T08:02:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/biscotti-e-croissant-ottimini-riso-e-mais-400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@divellaofficial\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/ottimini-riso-e-mais\\\/\",\"url\":\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/ottimini-riso-e-mais\\\/\",\"name\":\"Ottimini riso e mais - Divella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/ottimini-riso-e-mais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/ottimini-riso-e-mais\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/biscotti-e-croissant-ottimini-riso-e-mais-400-1.jpg\",\"datePublished\":\"2022-12-02T14:21:37+00:00\",\"dateModified\":\"2026-07-15T08:02:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/ottimini-riso-e-mais\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/ottimini-riso-e-mais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/ottimini-riso-e-mais\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/biscotti-e-croissant-ottimini-riso-e-mais-400-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/biscotti-e-croissant-ottimini-riso-e-mais-400-1.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/ottimini-riso-e-mais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.divella.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prodotti\",\"item\":\"https:\\\/\\\/www.divella.it\\\/it\\\/prodotti\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ottimini riso e mais\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.divella.it\\\/it\\\/\",\"name\":\"Divella\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.divella.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/#organization\",\"name\":\"Divella\",\"url\":\"https:\\\/\\\/www.divella.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-divella.jpg\",\"contentUrl\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-divella.jpg\",\"width\":200,\"height\":151,\"caption\":\"Divella\"},\"image\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Divella.IT\\\/\",\"https:\\\/\\\/x.com\\\/divellaofficial\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCfw9Jp-BYRM0T9qWR7RQK7A\",\"https:\\\/\\\/www.instagram.com\\\/divellaofficial\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/f.-divella-spa\\\/?originalSubdomain=it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ottimini riso e mais - Divella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/","og_locale":"it_IT","og_type":"article","og_title":"Ottimini riso e mais - Divella","og_description":"Caratterizzato dal perfetto connubio fra riso e mais soffiati che lo rendono gustoso e croccante, pu\u00f2 essere consumato in qualsiasi momento della giornata, anche come snack.","og_url":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/","og_site_name":"Divella","article_publisher":"https:\/\/www.facebook.com\/Divella.IT\/","article_modified_time":"2026-07-15T08:02:24+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/biscotti-e-croissant-ottimini-riso-e-mais-400-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@divellaofficial","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/","url":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/","name":"Ottimini riso e mais - Divella","isPartOf":{"@id":"https:\/\/www.divella.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/#primaryimage"},"image":{"@id":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/biscotti-e-croissant-ottimini-riso-e-mais-400-1.jpg","datePublished":"2022-12-02T14:21:37+00:00","dateModified":"2026-07-15T08:02:24+00:00","breadcrumb":{"@id":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/#primaryimage","url":"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/biscotti-e-croissant-ottimini-riso-e-mais-400-1.jpg","contentUrl":"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/biscotti-e-croissant-ottimini-riso-e-mais-400-1.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.divella.it\/it\/prodotti\/ottimini-riso-e-mais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.divella.it\/it\/"},{"@type":"ListItem","position":2,"name":"Prodotti","item":"https:\/\/www.divella.it\/it\/prodotti\/"},{"@type":"ListItem","position":3,"name":"Ottimini riso e mais"}]},{"@type":"WebSite","@id":"https:\/\/www.divella.it\/it\/#website","url":"https:\/\/www.divella.it\/it\/","name":"Divella","description":"","publisher":{"@id":"https:\/\/www.divella.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.divella.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.divella.it\/it\/#organization","name":"Divella","url":"https:\/\/www.divella.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.divella.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.divella.it\/wp-content\/uploads\/2023\/01\/logo-divella.jpg","contentUrl":"https:\/\/www.divella.it\/wp-content\/uploads\/2023\/01\/logo-divella.jpg","width":200,"height":151,"caption":"Divella"},"image":{"@id":"https:\/\/www.divella.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Divella.IT\/","https:\/\/x.com\/divellaofficial","https:\/\/www.youtube.com\/channel\/UCfw9Jp-BYRM0T9qWR7RQK7A","https:\/\/www.instagram.com\/divellaofficial\/?hl=it","https:\/\/www.linkedin.com\/company\/f.-divella-spa\/?originalSubdomain=it"]}]}},"_links":{"self":[{"href":"https:\/\/www.divella.it\/it\/wp-json\/wp\/v2\/prodotti\/2536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.divella.it\/it\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/www.divella.it\/it\/wp-json\/wp\/v2\/types\/prodotti"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.divella.it\/it\/wp-json\/wp\/v2\/media\/3694"}],"wp:attachment":[{"href":"https:\/\/www.divella.it\/it\/wp-json\/wp\/v2\/media?parent=2536"}],"wp:term":[{"taxonomy":"tipo-prodotto","embeddable":true,"href":"https:\/\/www.divella.it\/it\/wp-json\/wp\/v2\/tipo-prodotto?post=2536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}