{"id":4361,"date":"2022-12-05T16:04:48","date_gmt":"2022-12-05T15:04:48","guid":{"rendered":"https:\/\/www.divella.it\/prodotti\/93-capelli-dangelo\/"},"modified":"2023-01-31T11:07:04","modified_gmt":"2023-01-31T10:07:04","slug":"93-capelli-dangelo","status":"publish","type":"prodotti","link":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/","title":{"rendered":"93 &#8211; Capelli d\u2019Angelo"},"excerpt":{"rendered":"<p>The most delicate of semolina nests, ideal with simple or more elaborate condiments.<\/p>\n","protected":false},"featured_media":3253,"template":"","tipo-prodotto":[114],"class_list":["post-4361","prodotti","type-prodotti","status-publish","has-post-thumbnail","hentry","tipo-prodotto-specialities"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>93 - Capelli d\u2019Angelo - Divella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"93 - Capelli d\u2019Angelo - Divella\" \/>\n<meta property=\"og:description\" content=\"The most delicate of semolina nests, ideal with simple or more elaborate condiments.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/\" \/>\n<meta property=\"og:site_name\" content=\"Divella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Divella.IT\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-31T10:07:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/Divella-pasta-di-semola-specialita-capelli-d-angelo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@divellaofficial\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/93-capelli-dangelo\\\/\",\"url\":\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/93-capelli-dangelo\\\/\",\"name\":\"93 - Capelli d\u2019Angelo - Divella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/93-capelli-dangelo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/93-capelli-dangelo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Divella-pasta-di-semola-specialita-capelli-d-angelo.jpg\",\"datePublished\":\"2022-12-05T15:04:48+00:00\",\"dateModified\":\"2023-01-31T10:07:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/93-capelli-dangelo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/93-capelli-dangelo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/93-capelli-dangelo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Divella-pasta-di-semola-specialita-capelli-d-angelo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Divella-pasta-di-semola-specialita-capelli-d-angelo.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/93-capelli-dangelo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.divella.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/www.divella.it\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"93 &#8211; Capelli d\u2019Angelo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.divella.it\\\/en\\\/\",\"name\":\"Divella\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.divella.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/#organization\",\"name\":\"Divella\",\"url\":\"https:\\\/\\\/www.divella.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-divella.jpg\",\"contentUrl\":\"https:\\\/\\\/www.divella.it\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/logo-divella.jpg\",\"width\":200,\"height\":151,\"caption\":\"Divella\"},\"image\":{\"@id\":\"https:\\\/\\\/www.divella.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Divella.IT\\\/\",\"https:\\\/\\\/x.com\\\/divellaofficial\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCfw9Jp-BYRM0T9qWR7RQK7A\",\"https:\\\/\\\/www.instagram.com\\\/divellaofficial\\\/?hl=it\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/f.-divella-spa\\\/?originalSubdomain=it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"93 - Capelli d\u2019Angelo - Divella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/","og_locale":"en_US","og_type":"article","og_title":"93 - Capelli d\u2019Angelo - Divella","og_description":"The most delicate of semolina nests, ideal with simple or more elaborate condiments.","og_url":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/","og_site_name":"Divella","article_publisher":"https:\/\/www.facebook.com\/Divella.IT\/","article_modified_time":"2023-01-31T10:07:04+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/Divella-pasta-di-semola-specialita-capelli-d-angelo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@divellaofficial","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/","url":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/","name":"93 - Capelli d\u2019Angelo - Divella","isPartOf":{"@id":"https:\/\/www.divella.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/#primaryimage"},"image":{"@id":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/Divella-pasta-di-semola-specialita-capelli-d-angelo.jpg","datePublished":"2022-12-05T15:04:48+00:00","dateModified":"2023-01-31T10:07:04+00:00","breadcrumb":{"@id":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/#primaryimage","url":"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/Divella-pasta-di-semola-specialita-capelli-d-angelo.jpg","contentUrl":"https:\/\/www.divella.it\/wp-content\/uploads\/2022\/12\/Divella-pasta-di-semola-specialita-capelli-d-angelo.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.divella.it\/en\/products\/93-capelli-dangelo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.divella.it\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.divella.it\/en\/products\/"},{"@type":"ListItem","position":3,"name":"93 &#8211; Capelli d\u2019Angelo"}]},{"@type":"WebSite","@id":"https:\/\/www.divella.it\/en\/#website","url":"https:\/\/www.divella.it\/en\/","name":"Divella","description":"","publisher":{"@id":"https:\/\/www.divella.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.divella.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.divella.it\/en\/#organization","name":"Divella","url":"https:\/\/www.divella.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.divella.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.divella.it\/wp-content\/uploads\/2023\/01\/logo-divella.jpg","contentUrl":"https:\/\/www.divella.it\/wp-content\/uploads\/2023\/01\/logo-divella.jpg","width":200,"height":151,"caption":"Divella"},"image":{"@id":"https:\/\/www.divella.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Divella.IT\/","https:\/\/x.com\/divellaofficial","https:\/\/www.youtube.com\/channel\/UCfw9Jp-BYRM0T9qWR7RQK7A","https:\/\/www.instagram.com\/divellaofficial\/?hl=it","https:\/\/www.linkedin.com\/company\/f.-divella-spa\/?originalSubdomain=it"]}]}},"_links":{"self":[{"href":"https:\/\/www.divella.it\/en\/wp-json\/wp\/v2\/prodotti\/4361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.divella.it\/en\/wp-json\/wp\/v2\/prodotti"}],"about":[{"href":"https:\/\/www.divella.it\/en\/wp-json\/wp\/v2\/types\/prodotti"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.divella.it\/en\/wp-json\/wp\/v2\/media\/3253"}],"wp:attachment":[{"href":"https:\/\/www.divella.it\/en\/wp-json\/wp\/v2\/media?parent=4361"}],"wp:term":[{"taxonomy":"tipo-prodotto","embeddable":true,"href":"https:\/\/www.divella.it\/en\/wp-json\/wp\/v2\/tipo-prodotto?post=4361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}